{"id":248747,"date":"2014-06-18T23:32:45","date_gmt":"2014-06-18T22:32:45","guid":{"rendered":"https:\/\/nueva.depuragua.com\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/"},"modified":"2014-06-18T23:32:45","modified_gmt":"2014-06-18T22:32:45","slug":"ricambio-rimineralizzante-rubinetto-doccia-no-cloro","status":"publish","type":"product","link":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/","title":{"rendered":"Ricambio rimineralizzante rubinetto doccia NO CLORO"},"content":{"rendered":"<p>Ricambio rimineralizzante rubinetto doccia NO CLORO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricambio rimineralizzante rubinetto doccia NO CLORO<\/p>\n","protected":false},"featured_media":286715,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[1764],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ricambio rimineralizzante rubinetto doccia NO CLORO<\/title>\n<meta name=\"description\" content=\"Ricambio rimineralizzante rubinetto doccia NO CLORO\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ricambio rimineralizzante rubinetto doccia NO CLORO\" \/>\n<meta property=\"og:description\" content=\"Ricambio rimineralizzante rubinetto doccia NO CLORO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/\" \/>\n<meta property=\"og:site_name\" content=\"Depuragua\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depuraguaonline\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2014\/06\/522-thickbox_default-Osmosis-domestica-RO-50G-A01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AquatechIntl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/\",\"url\":\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/\",\"name\":\"Ricambio rimineralizzante rubinetto doccia NO CLORO\",\"isPartOf\":{\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#website\"},\"datePublished\":\"2014-06-18T22:32:45+00:00\",\"dateModified\":\"2014-06-18T22:32:45+00:00\",\"description\":\"Ricambio rimineralizzante rubinetto doccia NO CLORO\",\"breadcrumb\":{\"@id\":\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/tienda.depuragua.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/tienda.depuragua.com\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ricambio rimineralizzante rubinetto doccia NO CLORO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#website\",\"url\":\"https:\/\/tienda.depuragua.com\/it\/\",\"name\":\"Depuragua\",\"description\":\"Depuragua\",\"publisher\":{\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tienda.depuragua.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#organization\",\"name\":\"Depuragua\",\"url\":\"https:\/\/tienda.depuragua.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2023\/11\/logodepuragua.png\",\"contentUrl\":\"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2023\/11\/logodepuragua.png\",\"width\":1000,\"height\":340,\"caption\":\"Depuragua\"},\"image\":{\"@id\":\"https:\/\/tienda.depuragua.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/depuraguaonline\",\"https:\/\/twitter.com\/AquatechIntl\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ricambio rimineralizzante rubinetto doccia NO CLORO","description":"Ricambio rimineralizzante rubinetto doccia NO CLORO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/","og_locale":"it_IT","og_type":"article","og_title":"Ricambio rimineralizzante rubinetto doccia NO CLORO","og_description":"Ricambio rimineralizzante rubinetto doccia NO CLORO","og_url":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/","og_site_name":"Depuragua","article_publisher":"https:\/\/www.facebook.com\/depuraguaonline","og_image":[{"width":800,"height":800,"url":"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2014\/06\/522-thickbox_default-Osmosis-domestica-RO-50G-A01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AquatechIntl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/","url":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/","name":"Ricambio rimineralizzante rubinetto doccia NO CLORO","isPartOf":{"@id":"https:\/\/tienda.depuragua.com\/it\/#website"},"datePublished":"2014-06-18T22:32:45+00:00","dateModified":"2014-06-18T22:32:45+00:00","description":"Ricambio rimineralizzante rubinetto doccia NO CLORO","breadcrumb":{"@id":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tienda.depuragua.com\/it\/producto\/ricambio-rimineralizzante-rubinetto-doccia-no-cloro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tienda.depuragua.com\/it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/tienda.depuragua.com\/"},{"@type":"ListItem","position":3,"name":"Ricambio rimineralizzante rubinetto doccia NO CLORO"}]},{"@type":"WebSite","@id":"https:\/\/tienda.depuragua.com\/it\/#website","url":"https:\/\/tienda.depuragua.com\/it\/","name":"Depuragua","description":"Depuragua","publisher":{"@id":"https:\/\/tienda.depuragua.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tienda.depuragua.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tienda.depuragua.com\/it\/#organization","name":"Depuragua","url":"https:\/\/tienda.depuragua.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tienda.depuragua.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2023\/11\/logodepuragua.png","contentUrl":"https:\/\/tienda.depuragua.com\/wp-content\/uploads\/2023\/11\/logodepuragua.png","width":1000,"height":340,"caption":"Depuragua"},"image":{"@id":"https:\/\/tienda.depuragua.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/depuraguaonline","https:\/\/twitter.com\/AquatechIntl"]}]}},"_links":{"self":[{"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/product\/248747"}],"collection":[{"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/comments?post=248747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/media\/286715"}],"wp:attachment":[{"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/media?parent=248747"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/product_cat?post=248747"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tienda.depuragua.com\/it\/wp-json\/wp\/v2\/product_tag?post=248747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}